{"id":1510,"date":"2026-01-24T11:48:08","date_gmt":"2026-01-24T03:48:08","guid":{"rendered":"https:\/\/haoyumaterial.com\/?p=1510"},"modified":"2026-01-24T11:49:23","modified_gmt":"2026-01-24T03:49:23","slug":"casting-stainless-steel-guide-high-precision-processes-and-alloys","status":"publish","type":"post","link":"https:\/\/haoyumaterial.com\/it\/casting-stainless-steel-guide-high-precision-processes-and-alloys\/","title":{"rendered":"Colata di acciaio inossidabile guida processi di alta precisione e leghe"},"content":{"rendered":"<h2 class=\"wp-block-heading\">La vera verit\u00e0 sulla colata di acciaio inossidabile: il nostro processo di silice sol<\/h2>\n\n\n\n<p>Da Haoyu Material, trattiamo&nbsp;<strong>fusione in acciaio inossidabile<\/strong>&nbsp;come una scienza esatta, non solo un'operazione di fonderia. Sebbene ci siano molteplici modi per colare il metallo, ci impegniamo rigorosamente nel&nbsp;<strong>processo di colata a investimento con silice sol<\/strong>&nbsp;per i nostri componenti in acciaio inossidabile. Questa decisione non riguarda il risparmio sui costi; si tratta di fornire parti che soddisfano le rigorose esigenze di applicazioni marine, industriali e di gestione dei fluidi.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Perch\u00e9 scegliamo Silica Sol invece di vetro d'acqua<\/h3>\n\n\n\n<p>Nel mondo della&nbsp;<strong>fusione a cera persa<\/strong>, in genere hai due opzioni di incollaggio: Vetro d'acqua e Sol Silica. Utilizziamo esclusivamente il&nbsp;<strong>processo di Sol Silica<\/strong>&nbsp;per le nostre parti in acciaio inossidabile per motivi di ingegneria specifici:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Finitura superficiale superiore:<\/strong>\u00a0La colata con Sol Silica raggiunge una rugosit\u00e0 superficiale significativamente inferiore (valori Ra), eliminando spesso la necessit\u00e0 di una lucidatura secondaria estesa.<\/li>\n\n\n\n<li><strong>Precisione dimensionale:<\/strong>\u00a0Ci permette di mantenere tolleranze lineari pi\u00f9 strette (tipicamente\u00a0<strong>CT5\u2013CT7<\/strong>) rispetto al metodo pi\u00f9 ruvido del vetro d'acqua.<\/li>\n\n\n\n<li><strong>Geometrie complesse:<\/strong>\u00a0Questo metodo supporta dettagli intricati, pareti sottili e passaggi interni complessi essenziali per corpi valvole e giranti di pompe.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Passo dopo passo: il flusso di lavoro della cera persa<\/h3>\n\n\n\n<p>La nostra linea di produzione segue un protocollo rigoroso per garantire che ogni&nbsp;<strong>fusione in acciaio inossidabile<\/strong>&nbsp;mantenga l'integrit\u00e0 strutturale e la precisione dimensionale.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Iniezione del Modello in Cera:<\/strong>\u00a0Iniziamo iniettando cera fusa in stampi in alluminio ad alta precisione. Questo crea una replica esatta del vostro pezzo finale.<\/li>\n\n\n\n<li><strong>Edificio Shell:<\/strong>\u00a0I modelli di cera vengono assemblati su un \u201calbero\u201d e immersi in una sospensione di ceramica di alta qualit\u00e0. Applichiamo pi\u00f9 strati di sabbia fine (stucco) per costruire un guscio robusto in grado di resistere alla pressione dell'acciaio fuso.<\/li>\n\n\n\n<li><strong>Deceratura e sinterizzazione:<\/strong>\u00a0Posizioniamo il guscio in un autoclave per sciogliere la cera (da qui \u201ccera persa\u201d), lasciando una cavit\u00e0 vuota. Il guscio di ceramica viene poi cotto (sintronato) ad alte temperature per rafforzarlo prima della colata.<\/li>\n\n\n\n<li><strong>Fase critica di colata:<\/strong>\u00a0Versiamo acciaio inossidabile fuso\u2014che sia\u00a0<strong>304, 316 o Duplex 2205<\/strong>\u2014 nelle conchiglie preriscaldate. Controllare la temperatura qui \u00e8 fondamentale per prevenire porosit\u00e0 e difetti di restringimento.<\/li>\n\n\n\n<li><strong>Rettifica di scarico e gate:<\/strong>\u00a0Una volta raffreddate, vibramo la conchiglia ceramica via dal metallo. I pezzi vengono tagliati dall\u2019albero di assemblaggio e i residui del gate vengono levigati a filo per adattarsi alla geometria del pezzo.<\/li>\n<\/ol>\n\n\n\n<p>Questo processo rigoroso garantisce che quando ordini una&nbsp;<strong>fusione in acciaio inossidabile<\/strong>&nbsp;soluzione da noi, ricevi un componente pronto per la lavorazione finale o l\u2019assemblaggio immediato.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Scegliere il grado giusto per la fusione di parti in acciaio inossidabile<\/h2>\n\n\n\n<p>Quando gestiamo&nbsp;<strong>fusione in acciaio inossidabile<\/strong>&nbsp;progetti, la prima conversazione riguarda sempre il metallo stesso. Scegliere la lega sbagliata pu\u00f2 portare a guasti prematuri, mentre sovra-specificare aumenta inutilmente i costi. Guidiamo i nostri clienti nella selezione della qualit\u00e0 specifica che bilancia&nbsp;<strong>resistenza alla corrosione<\/strong>&nbsp;con le prestazioni meccaniche.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La suddivisione della Serie 300: 304 vs. 316L<\/h3>\n\n\n\n<p>Per la maggior parte delle applicazioni generali,&nbsp;<strong>Acciaio inossidabile austenitico<\/strong>&nbsp;\u00e8 lo standard del settore grazie alla sua eccellente duttilit\u00e0 e resistenza. Castiamo frequentemente queste due principali qualit\u00e0:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Acciaio inossidabile 304:<\/strong>\u00a0Questa \u00e8 la lega pi\u00f9 versatile. Offre una solida durata per macchinari alimentari, raccordi architettonici e parti industriali generali dove l'esposizione chimica estrema non \u00e8 un fattore.<\/li>\n\n\n\n<li><strong>Acciaio inossidabile 316\/316L:<\/strong>\u00a0Se i tuoi componenti sono esposti all'acqua salata o a ambienti chimici aggressivi, consigliamo questa qualit\u00e0. L'aggiunta di molibdeno aumenta significativamente la resistenza alla corrosione da fessurazione e da crepa. Puoi consultare le nostre capacit\u00e0 specifiche in\u00a0<a href=\"https:\/\/haoyumaterial.com\/it\/stainless-steel-cast\/\">fusione di acciaio inossidabile<\/a>\u00a0per vedere come lavoriamo queste leghe comuni per una finitura superficiale ottimale.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Leghe ad alte prestazioni: 17-4 PH e Duplex<\/h3>\n\n\n\n<p>A volte, la resistenza alla corrosione standard non \u00e8 sufficiente; hai bisogno di pura forza o propriet\u00e0 specializzate.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Lega 17-4 PH:<\/strong>\u00a0Quando alta\u00a0<strong>resistenza alla trazione<\/strong>\u00a0e durezza sono non negoziabili, ci rivolgiamo a questa lega a indurimento per precipitazione. \u00c8 ideale per alberi di pompe, steli di valvole e componenti aerospaziali che devono resistere a stress elevati senza deformarsi.<\/li>\n\n\n\n<li><strong>Acciaio inossidabile duplex (2205):<\/strong>\u00a0Per ambienti estremi che richiedono sia alta resistenza che superiore resistenza alla criccatura da stress, il Duplex \u00e8 la scelta superiore rispetto alle leghe austenitiche standard.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Garantire la purezza della lega<\/h3>\n\n\n\n<p>Non lasciamo la composizione del materiale al caso. Prima di ogni colata, utilizziamo uno spettrometro per analizzare la composizione chimica esatta del metallo fuso. Questo passaggio di controllo qualit\u00e0 garantisce che ogni lotto rispetti rigorosi standard internazionali (ASTM, DIN) e assicura l'integrit\u00e0 dei tuoi pezzi finali.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Regole di progettazione intelligenti per la fusione dell'acciaio inossidabile<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/haoyumaterial.com\/wp-content\/uploads\/2026\/01\/casting_stainless_steel_design_rules_dCKdzfNEh.webp\" alt=\"regole di progettazione per la fusione in acciaio inossidabile\"\/><\/figure>\n\n\n\n<p>Ottimi pezzi iniziano con un ingegneria intelligente. Quando siamo&nbsp;<strong>fusione in acciaio inossidabile<\/strong>, aderendo a linee guida di progettazione specifiche, si garantisce che il componente finale funzioni esattamente come previsto senza costi o ritardi inutili. Collaboriamo strettamente con gli ingegneri per ottimizzare i disegni per il processo di produzione, assicurando alti rendimenti e superiore integrit\u00e0 strutturale.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Gestione delle tolleranze dimensionali<\/h3>\n\n\n\n<p>La precisione \u00e8 il marchio distintivo del nostro processo di silice sol. Di solito ci atteniamo a&nbsp;<strong>gli standard ISO 8062<\/strong>, mantenendo tolleranze dimensionali lineari tra&nbsp;<strong>CT5 e CT7<\/strong>. Questo livello di precisione ci consente di produrre geometrie complesse che spesso richiedono poca o nessuna lavorazione secondaria. Per caratteristiche che richiedono adattamenti pi\u00f9 stretti rispetto a quanto permette il processo di fusione, integriamo la lavorazione di precisione direttamente presso il nostro&nbsp;<strong><a href=\"https:\/\/haoyumaterial.com\/it\/lost-wax-casting-foundry\/\">fonderia di fusione a cera persa<\/a><\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Raccomandazioni Critiche di Progettazione<\/h3>\n\n\n\n<p>Per garantire una fusione di successo, tieni presente questi parametri:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Spessore minimo delle pareti:<\/strong>\u00a0Per la maggior parte delle leghe di acciaio inossidabile, consigliamo uno spessore minimo di parete di\u00a0<strong>1,5 mm a 2 mm.<\/strong>. Questo garantisce che il metallo fuso fluisca completamente nello stampo prima di solidificarsi, prevenendo difetti come mancate colate o raffreddamenti prematuri.<\/li>\n\n\n\n<li><strong>Angoli di inclinazione:<\/strong>\u00a0Sebbene la fusione a cera persa sia nota per gestire meglio i sottosquadri rispetto ad altri metodi, aggiungere un leggero angolo di smusso (0,5\u00b0 a 1\u00b0) aiuta notevolmente nella liberazione del modello di cera dalla matrice. Questo riduce l'usura degli stampi e migliora la consistenza superficiale.<\/li>\n\n\n\n<li><strong>Radii e smussi:<\/strong>\u00a0Gli angoli acuti sono concentratori di stress che possono portare a crepe durante la fase di raffreddamento. Consigliamo sempre di aggiungere radii e smussi agli angoli interni ed esterni. Questo semplice accorgimento previene la rottura a caldo e rende il pezzo pi\u00f9 resistente e duraturo.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Finiture: lavorazioni meccaniche e lucidatura dell'acciaio inossidabile fuso<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/haoyumaterial.com\/wp-content\/uploads\/2026\/01\/cast_stainless_machining_and_polishing_techniques.webp\" alt=\"tecniche di fusione e lucidatura dell&#039;acciaio inossidabile\"\/><\/figure>\n\n\n\n<p>Mentre il nostro processo con solfuro di silice garantisce una qualit\u00e0 superficiale eccellente direttamente dallo stampo, molte applicazioni industriali richiedono operazioni secondarie per soddisfare le specifiche finali. Offriamo una soluzione completa \u201cchiavi in mano\u201d, partendo dal materiale grezzo.&nbsp;<strong>fusione in acciaio inossidabile<\/strong>&nbsp;parti attraverso lavorazioni di precisione e trattamenti superficiali avanzati affinch\u00e9 arrivino pronti per l'assemblaggio.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Lavorazioni secondarie di precisione CNC<\/h3>\n\n\n\n<p>La fusione a investimento ci avvicina molto alla forma finale, raggiungendo tipicamente tolleranze intorno a CT5\u2013CT7. Tuttavia, per superfici di accoppiamento critiche, adattamenti di cuscinetti o fori filettati,&nbsp;<strong>Lavorazioni secondarie CNC<\/strong>&nbsp;\u00e8 essenziale. Integramo le lavorazioni direttamente nella nostra linea di produzione, garantendo che la transizione dalla fusione alla finitura sia senza soluzione di continuit\u00e0.<\/p>\n\n\n\n<p>Gestendo sia la fonderia che il reparto macchine, eliminiamo le incomprensioni che spesso si verificano tra fornitori separati. Per un approfondimento su come gestiamo queste specifiche strette, consulta la nostra guida su&nbsp;<a href=\"https:\/\/haoyumaterial.com\/it\/machining-casting-guide-precision-cnc-tight-tolerances\/\">lavorazioni di precisione CNC e tolleranze di fusione<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Trattamenti superficiali per funzione ed estetica<\/h3>\n\n\n\n<p>L'acciaio inossidabile viene scelto per la sua durabilit\u00e0 e aspetto, ma la superficie grezza della fusione spesso necessita di perfezionamenti. Offriamo una gamma di finiture su misura per l'ambiente specifico in cui il pezzo sar\u00e0 utilizzato:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Lucidatura a specchio:<\/strong>\u00a0Essenziale per hardware marino e accessori architettonici dove l'aspetto visivo \u00e8 fondamentale. Levighiamo e lucidiamo la superficie per una finitura lucida e riflettente.<\/li>\n\n\n\n<li><strong>Elettropolishing:<\/strong>\u00a0Questo processo elettrochimico rimuove il materiale superficiale a livello microscopico. \u00c8 fondamentale per le industrie alimentari e mediche poich\u00e9 riduce\u00a0<strong>i valori di rugosit\u00e0 superficiale Ra<\/strong>, prevenendo l'accumulo di batteri e facilitando la pulizia.<\/li>\n\n\n\n<li><strong>Decapaggio e Passivazione:<\/strong>\u00a0Dopo la fusione e l'utensile, lo strato protettivo naturale di ossido dell'acciaio inossidabile pu\u00f2 essere compromesso. Usiamo decapaggio e passivazione per rimuovere contaminanti superficiali (come il ferro libero) e ripristinare al massimo le propriet\u00e0 del materiale.\u00a0<strong>resistenza alla corrosione<\/strong>.<\/li>\n\n\n\n<li><strong>Sabbiatura:<\/strong>\u00a0Per parti che richiedono una texture opaca e uniforme, la sabbiatura offre un aspetto pulito e coerente che nasconde piccole imperfezioni superficiali.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Dove utilizziamo le soluzioni di fusione in acciaio inossidabile<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"632\" height=\"367\" src=\"https:\/\/haoyumaterial.com\/wp-content\/uploads\/2026\/01\/stainless-casting.png\" alt=\"\" class=\"wp-image-1511\" srcset=\"https:\/\/haoyumaterial.com\/wp-content\/uploads\/2026\/01\/stainless-casting.png 632w, https:\/\/haoyumaterial.com\/wp-content\/uploads\/2026\/01\/stainless-casting-300x174.png 300w, https:\/\/haoyumaterial.com\/wp-content\/uploads\/2026\/01\/stainless-casting-18x10.png 18w, https:\/\/haoyumaterial.com\/wp-content\/uploads\/2026\/01\/stainless-casting-600x348.png 600w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><\/figure>\n\n\n\n<p>Il nostro&nbsp;<strong>fusione in acciaio inossidabile<\/strong>&nbsp;le capacit\u00e0 coprono un'ampia gamma di settori. Poich\u00e9 utilizziamo il processo di fusione a investimento di precisione (cera persa), possiamo adattarci a requisiti rigorosi che l'elemento sia immerso in acqua salata o che elabori alimenti. Non versiamo semplicemente metallo; progettiamo soluzioni per ambienti specifici utilizzando acciai inossidabili austenitici e martensitici di alta qualit\u00e0.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Ferramenta marina:<\/strong>\u00a0Produciamo componenti robusti come ganci, cunei, ancore e cerniere. Per queste applicazioni, di solito fonderiamo acciaio inossidabile 316 per garantire la massima\u00a0<strong>resistenza alla corrosione<\/strong>\u00a0resistenza alle condizioni aggressive dell'acqua salata.<\/li>\n\n\n\n<li><strong>Sistemi di gestione dei fluidi:<\/strong>\u00a0Questo \u00e8 uno dei nostri settori pi\u00f9 grandi. Produciamo giranti complesse, raccordi per tubi e\u00a0<a href=\"https:\/\/haoyumaterial.com\/it\/valve-castings-manufacturer-custom-oem-valve-bodies\/\">corpi valvola OEM personalizzati<\/a>\u00a0che richiedono tolleranze di tenuta di pressione molto strette. Il processo di solfuro di silice garantisce i passaggi interni lisci necessari per un flusso efficiente.<\/li>\n\n\n\n<li><strong>Macchinari sanitari:<\/strong>\u00a0Per i settori alimentare e medico, la finitura superficiale \u00e8 non negoziabile.<\/li>\n\n\n\n<li><strong>Forniamo parti elettropolished per rispettare gli standard igienici, assicurando che non ci siano fessure dove possano nascondersi batteri.<\/strong>\u00a0Componenti Architettonici:\u00a0<a href=\"https:\/\/haoyumaterial.com\/it\/stainless-steel-casting-process\/\">processo di fusione dell'acciaio inossidabile<\/a>\u00a0Realizziamo parti strutturali ma estetiche come ragni in vetro e staffe robuste.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Queste spesso subiscono il nostro trattamento completo<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">seguito dalla lucidatura a specchio per combinare resistenza portante con un aspetto architettonico di alta qualit\u00e0.<\/h3>\n\n\n\n<p>Domande frequenti sui progetti di fusione in acciaio inossidabile,&nbsp;<strong>fusione in acciaio inossidabile<\/strong>&nbsp;La fusione in acciaio inossidabile \u00e8 pi\u00f9 economica rispetto alla lavorazione CNC da un blocco solido?&nbsp;<a href=\"https:\/\/haoyumaterial.com\/it\/stainless-investment-casting-process-benefits-grades-and-costs\/\">vantaggi del processo di fusione a cera persa in acciaio inossidabile<\/a>&nbsp;il tuo margine di profitto abbassando il costo unitario. Tuttavia, per volumi estremamente bassi (come 1 a 5 pezzi) o forme molto semplici, la lavorazione da stock potrebbe essere pi\u00f9 veloce poich\u00e9 eviti la configurazione iniziale degli stampi.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Come si controlla la porosit\u00e0 nella fusione a cera persa?<\/h3>\n\n\n\n<p>La porosit\u00e0 \u00e8 il nemico dell'integrit\u00e0 strutturale. Gestiamo questo attraverso controlli rigorosi del processo nel nostro&nbsp;<strong>Fusione con Silica Sol<\/strong>&nbsp;metodo. Ottimizzando la progettazione del cancello e controllando la temperatura dello stampo durante la colata, garantiamo una corretta fuoriuscita dei gas e il flusso del metallo. Utilizziamo anche materie prime ad alta purezza per minimizzare i contaminanti. Per applicazioni critiche, verifichiamo la qualit\u00e0 interna tramite metodi di prova non distruttivi per garantire che i pezzi rispettino rigorosi standard industriali.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Quali sono i tempi di consegna tipici per nuovi stampi?<\/h3>\n\n\n\n<p>Poich\u00e9 ci specializziamo in pezzi personalizzati basati sui tuoi disegni, i tempi di consegna variano a seconda della complessit\u00e0 dello stampo. In generale, il processo include la progettazione dello stampo, la lavorazione dello stampo in alluminio e la produzione di campioni iniziali per l'approvazione. Mentre le staffe semplici si muovono rapidamente, quelle complesse&nbsp;<strong>fusione aerospaziale<\/strong>&nbsp;componenti o corpi di pompe intricati richiedono un po' pi\u00f9 di tempo per essere perfezionati. Ci concentriamo a ottenere il campione giusto al primo tentativo per facilitare la transizione alla produzione di massa.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Puoi gestire la prototipazione rapida prima della produzione di massa?<\/h3>\n\n\n\n<p>S\u00ec. Capisci che devi convalidare l'adattamento e la funzione prima di impegnarti in una produzione completa. Come fornitore di&nbsp;<strong>servizi di fusione OEM<\/strong>, supportiamo la prototipazione per verificare&nbsp;<strong>tolleranze dimensionali<\/strong>&nbsp;e la fattibilit\u00e0 del progetto. Questa fase ci permette di identificare potenziali problemi\u2014come aggiustamenti dell'angolo di scarico o preoccupazioni sulla spessore delle pareti\u2014assicurando che la produzione finale proceda senza intoppi.<\/p>","protected":false},"excerpt":{"rendered":"<p>The Real Deal on Casting Stainless: Our Silica Sol Process At Haoyu Material, we treat&nbsp;casting stainless&nbsp;as an exact science, not [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1512,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[420,66,421,68,419,164],"class_list":["post-1510","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blogs","tag-304-316l-casting","tag-lost-wax-casting","tag-marine-industrial-casting-components","tag-precision-casting","tag-silica-sol-investment-casting","tag-stainless-steel-casting"],"_links":{"self":[{"href":"https:\/\/haoyumaterial.com\/it\/wp-json\/wp\/v2\/posts\/1510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/haoyumaterial.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/haoyumaterial.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/haoyumaterial.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/haoyumaterial.com\/it\/wp-json\/wp\/v2\/comments?post=1510"}],"version-history":[{"count":1,"href":"https:\/\/haoyumaterial.com\/it\/wp-json\/wp\/v2\/posts\/1510\/revisions"}],"predecessor-version":[{"id":1515,"href":"https:\/\/haoyumaterial.com\/it\/wp-json\/wp\/v2\/posts\/1510\/revisions\/1515"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/haoyumaterial.com\/it\/wp-json\/wp\/v2\/media\/1512"}],"wp:attachment":[{"href":"https:\/\/haoyumaterial.com\/it\/wp-json\/wp\/v2\/media?parent=1510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/haoyumaterial.com\/it\/wp-json\/wp\/v2\/categories?post=1510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/haoyumaterial.com\/it\/wp-json\/wp\/v2\/tags?post=1510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}